{"id":359434,"date":"2024-11-14T17:48:57","date_gmt":"2024-11-14T16:48:57","guid":{"rendered":"https:\/\/www.arclite-shop.de\/produkt\/02-4099854091117\/"},"modified":"2026-04-16T14:22:01","modified_gmt":"2026-04-16T12:22:01","slug":"02-4099854091117","status":"publish","type":"product","link":"https:\/\/www.arclite-shop.de\/it\/produkt\/02-4099854091117\/","title":{"rendered":"Lampade LED, edizione vintage, con forma speciale di lampadina"},"content":{"rendered":"<p>LED-Lampen, Vintage-Edition. Produkteigenschaften: LED-Lampen f\u00fcr Netzspannung. Lampe aus Glas. Lebensdauer: bis zu 15.000 h. Ausstrahlungswinkel: bis zu 360\u00b0. Gute Lichtqualit\u00e4t; Farbwiedergabeindex Ra: \u2265 80; konstanter Farbort. Produktvorteile: Sehr geringer Energieverbrauch. Sofort 100 % Licht, keine Aufw\u00e4rmzeit. Einfacher Austausch von Standardgl\u00fchlampen. Lampen mit innovativer LED-&#8220;Filament&#8221;-Technologie. Anwendungsgebiete: Ideal f\u00fcr dekorative Einbauten. Anwendungen im Haushalt. Allgemeinbeleuchtung. Einsatz im Au\u00dfenbereich nur in geeigneten Au\u00dfenleuchten.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LED-Lampen, Vintage-Edition. Produkteigenschaften: LED-Lampen f\u00fcr Netzspannung. Lampe aus Glas. Lebensdauer: bis zu 15.000 h. Ausstrahlungswinkel: bis zu 360\u00b0. Gute Lichtqualit\u00e4t; Farbwiedergabeindex Ra: \u2265 80; konstanter Farbort. Produktvorteile: Sehr geringer Energieverbrauch. Sofort 100 % Licht, keine Aufw\u00e4rmzeit. Einfacher Austausch von Standardgl\u00fchlampen.<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"featured_media":363898,"template":"","meta":[],"product_brand":[],"product_cat":[87060],"product_tag":[],"class_list":{"0":"post-359434","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-led-lampe-multi-led","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/www.arclite-shop.de\/it\/wp-json\/wp\/v2\/product\/359434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arclite-shop.de\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.arclite-shop.de\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arclite-shop.de\/it\/wp-json\/wp\/v2\/media\/363898"}],"wp:attachment":[{"href":"https:\/\/www.arclite-shop.de\/it\/wp-json\/wp\/v2\/media?parent=359434"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.arclite-shop.de\/it\/wp-json\/wp\/v2\/product_brand?post=359434"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.arclite-shop.de\/it\/wp-json\/wp\/v2\/product_cat?post=359434"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.arclite-shop.de\/it\/wp-json\/wp\/v2\/product_tag?post=359434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}