{"id":352400,"date":"2024-10-31T17:41:07","date_gmt":"2024-10-31T16:41:07","guid":{"rendered":"https:\/\/www.arclite-shop.de\/produkt\/717-lxsdw80840le27wip20w3p\/"},"modified":"2026-04-16T23:39:11","modified_gmt":"2026-04-16T21:39:11","slug":"717-lxsdw80840le27wip20w3p","status":"publish","type":"product","link":"https:\/\/www.arclite-shop.de\/fr\/produkt\/717-lxsdw80840le27wip20w3p\/","title":{"rendered":"SNEP LX S - Projecteur de piste lin\u00e9aire blanc 27W 80\u00b0 4000K CRI80 717-LXSDW80840LE27WIP20W3P"},"content":{"rendered":"<p>Hochwertige 3-Ph-Linearleuchte. Geh\u00e4use aus Aluminiumprofil, pulverbeschichtet. Universeller Schienenadapter. Hervorragend Energieeffizienz und Lichtverteilung. Bildschirm-Arbeitsplatz geeignet UGR &lt; 19. Farbtoleranz 3 SDCM. Lichtstromr\u00fcckgang nach 100.000h L80\/B50 bei ta 25\u00b0C. Integriertes Betriebsger\u00e4t. 5 Jahre Garantie. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hochwertige 3-Ph-Linearleuchte. Geh\u00e4use aus Aluminiumprofil, pulverbeschichtet. Universeller Schienenadapter. Hervorragend Energieeffizienz und Lichtverteilung. Bildschirm-Arbeitsplatz geeignet UGR &lt; 19. Farbtoleranz 3 SDCM. Lichtstromr\u00fcckgang nach 100.000h L80\/B50 bei ta 25\u00b0C. Integriertes Betriebsger\u00e4t. 5 Jahre Garantie.<\/p>\n","protected":false},"featured_media":262018,"template":"","meta":[],"product_brand":[],"product_cat":[86138],"product_tag":[],"class_list":{"0":"post-352400","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-schienenstrahler-linear","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/www.arclite-shop.de\/fr\/wp-json\/wp\/v2\/product\/352400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arclite-shop.de\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.arclite-shop.de\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arclite-shop.de\/fr\/wp-json\/wp\/v2\/media\/262018"}],"wp:attachment":[{"href":"https:\/\/www.arclite-shop.de\/fr\/wp-json\/wp\/v2\/media?parent=352400"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.arclite-shop.de\/fr\/wp-json\/wp\/v2\/product_brand?post=352400"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.arclite-shop.de\/fr\/wp-json\/wp\/v2\/product_cat?post=352400"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.arclite-shop.de\/fr\/wp-json\/wp\/v2\/product_tag?post=352400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}