{"id":349201,"date":"2024-10-31T13:56:23","date_gmt":"2024-10-31T12:56:23","guid":{"rendered":"https:\/\/www.arclite-shop.de\/produkt\/03-44915200\/"},"modified":"2026-04-18T10:20:02","modified_gmt":"2026-04-18T08:20:02","slug":"03-44915200","status":"publish","type":"product","link":"https:\/\/www.arclite-shop.de\/fr\/produkt\/03-44915200\/","title":{"rendered":"MASTER LED SON-T - Lampe LED\/Multi-LED - Puissance syst\u00e8me : 50 W - Classe d\u2019efficacit\u00e9 \u00e9nerg\u00e9tique : C - Temp\u00e9rature de couleur la plus similaire (Nom) : 2700 K"},"content":{"rendered":"<p>Philips Master LED SON-T f\u00fcr den Stra\u00dfenbereich bieten eine einfache und sich schnell amortisierende LED-L\u00f6sung f\u00fcr den Austausch von konventionellen SON-T\/NAV-T Lampen. Die Lichtverteilung ist dabei nahezu identisch gegen\u00fcber herk\u00f6mmlichen L\u00f6sungen: die LEDs sind auf der gleichen H\u00f6he wie der Brenner herk\u00f6mmlicher SON-T\/NAV-T Lampen platziert und nutzen somit die Reflektoren und Optiken der bestehenden Leuchte optimal. Die Master LED SON-T ist als Retrofit oder f\u00fcr den direkten Betrieb an 230V Netzspannung erh\u00e4ltlich.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Philips Master LED SON-T f\u00fcr den Stra\u00dfenbereich bieten eine einfache und sich schnell amortisierende LED-L\u00f6sung f\u00fcr den Austausch von konventionellen SON-T\/NAV-T Lampen. Die Lichtverteilung ist dabei nahezu identisch gegen\u00fcber herk\u00f6mmlichen L\u00f6sungen: die LEDs sind auf der gleichen H\u00f6he wie der<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"featured_media":367556,"template":"","meta":[],"product_brand":[],"product_cat":[83758],"product_tag":[],"class_list":{"0":"post-349201","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-led-lampe-multi-led-signify","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/www.arclite-shop.de\/fr\/wp-json\/wp\/v2\/product\/349201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arclite-shop.de\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.arclite-shop.de\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arclite-shop.de\/fr\/wp-json\/wp\/v2\/media\/367556"}],"wp:attachment":[{"href":"https:\/\/www.arclite-shop.de\/fr\/wp-json\/wp\/v2\/media?parent=349201"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.arclite-shop.de\/fr\/wp-json\/wp\/v2\/product_brand?post=349201"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.arclite-shop.de\/fr\/wp-json\/wp\/v2\/product_cat?post=349201"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.arclite-shop.de\/fr\/wp-json\/wp\/v2\/product_tag?post=349201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}