{"id":347345,"date":"2024-10-31T11:34:11","date_gmt":"2024-10-31T10:34:11","guid":{"rendered":"https:\/\/www.arclite-shop.de\/produkt\/853-aa82780-01-94\/"},"modified":"2026-07-02T16:13:51","modified_gmt":"2026-07-02T14:13:51","slug":"853-aa82780-01-94","status":"publish","type":"product","link":"https:\/\/www.arclite-shop.de\/fr\/produkt\/853-aa82780-01-94\/","title":{"rendered":"linetrackCENTURY 32 - Projecteur de piste lin\u00e9aire, rotative, pivotant argent\u00e9 20W\/25W\/30W\/35W 60\u00b0 3500K CRI80 853-AA82780.01.94"},"content":{"rendered":"<p>Hochwertige 3-Ph-Linearleuchte. Geh\u00e4use aus Aluminiumprofil, pulverbeschichtet. 1-reihige hochwertige Linsenoptik. Verschiedene Ausf\u00fchrungen der Ausstrahloptiken, Licht- u. Geh\u00e4usefarben. DALI-Steuerung auf Anfrage. Einstellbare Leistung \u00fcber DIP-Schalter. Farbtoleranz 3 SDCM. Lichtstromr\u00fcckgang nach 55.000h L80\/B10. Integriertes, nicht dimmbares Betriebsger\u00e4t. Diese Leuchte enth\u00e4lt eine Lichtquelle der Energieeffizienzklasse C. 5 Jahre Garantie. Einstellbare Leistung 20W\/25W\/30W\/35W. Bis zu 158 lum\/W<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hochwertige 3-Ph-Linearleuchte. Geh\u00e4use aus Aluminiumprofil, pulverbeschichtet. 1-reihige hochwertige Linsenoptik. Verschiedene Ausf\u00fchrungen der Ausstrahloptiken, Licht- u. Geh\u00e4usefarben. DALI-Steuerung auf Anfrage. Einstellbare Leistung \u00fcber DIP-Schalter. Farbtoleranz 3 SDCM. Lichtstromr\u00fcckgang nach 55.000h L80\/B10. Integriertes, nicht dimmbares Betriebsger\u00e4t. Diese Leuchte enth\u00e4lt eine Lichtquelle der<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"featured_media":2676122,"template":"","meta":[],"product_brand":[],"product_cat":[92937,86138,86140],"product_tag":[],"class_list":["post-347345","product","type-product","status-publish","has-post-thumbnail","product_cat-drehbar","product_cat-schienenstrahler-linear","product_cat-schwenkbar","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/www.arclite-shop.de\/fr\/wp-json\/wp\/v2\/product\/347345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arclite-shop.de\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.arclite-shop.de\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arclite-shop.de\/fr\/wp-json\/wp\/v2\/media\/2676122"}],"wp:attachment":[{"href":"https:\/\/www.arclite-shop.de\/fr\/wp-json\/wp\/v2\/media?parent=347345"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.arclite-shop.de\/fr\/wp-json\/wp\/v2\/product_brand?post=347345"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.arclite-shop.de\/fr\/wp-json\/wp\/v2\/product_cat?post=347345"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.arclite-shop.de\/fr\/wp-json\/wp\/v2\/product_tag?post=347345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}