{"id":347523,"date":"2024-10-31T11:36:21","date_gmt":"2024-10-31T10:36:21","guid":{"rendered":"https:\/\/www.arclite-shop.de\/produkt\/119-ae82615-00-90\/"},"modified":"2026-04-18T11:12:50","modified_gmt":"2026-04-18T09:12:50","slug":"119-ae82615-00-90","status":"publish","type":"product","link":"https:\/\/www.arclite-shop.de\/es\/produkt\/119-ae82615-00-90\/","title":{"rendered":"trackCENTURY 15 - Foco giratorio de pista blanco  27W 12\u00b0 2700K CRI92 119-AE82615.00.90"},"content":{"rendered":"<p>Topaktueller, schlichter LED-Schienenstrahler im Retail f\u00fcr hohe Anspr\u00fcche. Hochdurchl\u00e4ssiges Schutzglas. Hocheffizienter, segmentierter Reflektor. Drehbereich 355\u00b0. Schwenkbereich 90\u00b0. Farbtoleranz 2 SDCM. Lichtstromr\u00fcckgang nach 50.000h L80\/B20. Farbtoleranz 3 SDCM. Universeller Schienenadapter. Integriertes, nicht dimmbares Betriebsger\u00e4t. 5 Jahre Garantie. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Topaktueller, schlichter LED-Schienenstrahler im Retail f\u00fcr hohe Anspr\u00fcche. Hochdurchl\u00e4ssiges Schutzglas. Hocheffizienter, segmentierter Reflektor. Drehbereich 355\u00b0. Schwenkbereich 90\u00b0. Farbtoleranz 2 SDCM. Lichtstromr\u00fcckgang nach 50.000h L80\/B20. Farbtoleranz 3 SDCM. Universeller Schienenadapter. Integriertes, nicht dimmbares Betriebsger\u00e4t. 5 Jahre Garantie.<\/p>\n","protected":false},"featured_media":367846,"template":"","meta":[],"product_brand":[],"product_cat":[85769],"product_tag":[],"class_list":{"0":"post-347523","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-schienenstrahler-dreh-schwenkbar","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/www.arclite-shop.de\/es\/wp-json\/wp\/v2\/product\/347523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arclite-shop.de\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.arclite-shop.de\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arclite-shop.de\/es\/wp-json\/wp\/v2\/media\/367846"}],"wp:attachment":[{"href":"https:\/\/www.arclite-shop.de\/es\/wp-json\/wp\/v2\/media?parent=347523"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.arclite-shop.de\/es\/wp-json\/wp\/v2\/product_brand?post=347523"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.arclite-shop.de\/es\/wp-json\/wp\/v2\/product_cat?post=347523"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.arclite-shop.de\/es\/wp-json\/wp\/v2\/product_tag?post=347523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}