{"id":346640,"date":"2024-10-31T11:21:22","date_gmt":"2024-10-31T10:21:22","guid":{"rendered":"https:\/\/www.arclite-shop.de\/produkt\/476-ae82734-00-90\/"},"modified":"2026-04-18T12:34:00","modified_gmt":"2026-04-18T10:34:00","slug":"476-ae82734-00-90","status":"publish","type":"product","link":"https:\/\/www.arclite-shop.de\/es\/produkt\/476-ae82734-00-90\/","title":{"rendered":"trackCENTURY 75 - Foco de pista giratorio blanco giratorio  22W 15\u00b0 2700K CRI92 476-AE82734.00.90"},"content":{"rendered":"<p>Hochmoderner, schlichter LED-Schienenstrahler \u2013 auch f\u00fcr niedrige Deckenh\u00f6hen geeignet. Facettierter Reflektor f\u00fcr optimale Lichtverteilung. Klares Schutzglas. Drehbereich 355\u00b0. Schwenkbereich 90\u00b0. Farbtoleranz 3 SDCM. Lichtstromr\u00fcckgang nach 50.000h L80\/B20. \u201cin-trac\u201d 3-Phasen Adapter mit integriertem Betriebsger\u00e4t, flickerfrei. 5 Jahre Garantie. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hochmoderner, schlichter LED-Schienenstrahler \u2013 auch f\u00fcr niedrige Deckenh\u00f6hen geeignet. Facettierter Reflektor f\u00fcr optimale Lichtverteilung. Klares Schutzglas. Drehbereich 355\u00b0. Schwenkbereich 90\u00b0. Farbtoleranz 3 SDCM. Lichtstromr\u00fcckgang nach 50.000h L80\/B20. \u201cin-trac\u201d 3-Phasen Adapter mit integriertem Betriebsger\u00e4t, flickerfrei. 5 Jahre Garantie.<\/p>\n","protected":false},"featured_media":346473,"template":"","meta":[],"product_brand":[],"product_cat":[85769],"product_tag":[],"class_list":{"0":"post-346640","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-schienenstrahler-dreh-schwenkbar","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/www.arclite-shop.de\/es\/wp-json\/wp\/v2\/product\/346640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arclite-shop.de\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.arclite-shop.de\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arclite-shop.de\/es\/wp-json\/wp\/v2\/media\/346473"}],"wp:attachment":[{"href":"https:\/\/www.arclite-shop.de\/es\/wp-json\/wp\/v2\/media?parent=346640"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.arclite-shop.de\/es\/wp-json\/wp\/v2\/product_brand?post=346640"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.arclite-shop.de\/es\/wp-json\/wp\/v2\/product_cat?post=346640"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.arclite-shop.de\/es\/wp-json\/wp\/v2\/product_tag?post=346640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}