{"id":355444,"date":"2024-10-31T18:19:35","date_gmt":"2024-10-31T17:19:35","guid":{"rendered":"https:\/\/www.arclite-shop.de\/produkt\/628-ae82793-02-91\/"},"modified":"2026-07-02T13:26:45","modified_gmt":"2026-07-02T11:26:45","slug":"628-ae82793-02-91","status":"publish","type":"product","link":"https:\/\/www.arclite-shop.de\/en\/produkt\/628-ae82793-02-91\/","title":{"rendered":"roundCENTURY 183 - Round recessed gimbal, black  33W 15\u00b0 3000K CRI90 AE82793.02.91"},"content":{"rendered":"<p>Kardanische LED Einbauleuchte f\u00fcr gehobene Anspr\u00fcche, im Retail vielseitig einsetzbar. F\u00fcr Allgemein- und Akzentbeleuchtung. Facettierter Reflektor f\u00fcr optimale Lichtverteilung. Schwenkbereich 30\u00b0. Drehbereich 330\u00b0. Farbtoleranz 3 SDCM. Lichtstromr\u00fcckgang nach 50.000h L80\/B20. Separates, nicht dimmbares Betriebsger\u00e4t. 5 Jahre Garantie<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kardanische LED Einbauleuchte f\u00fcr gehobene Anspr\u00fcche, im Retail vielseitig einsetzbar. F\u00fcr Allgemein- und Akzentbeleuchtung. Facettierter Reflektor f\u00fcr optimale Lichtverteilung. Schwenkbereich 30\u00b0. Drehbereich 330\u00b0. Farbtoleranz 3 SDCM. Lichtstromr\u00fcckgang nach 50.000h L80\/B20. Separates, nicht dimmbares Betriebsger\u00e4t. 5 Jahre Garantie<\/p>\n","protected":false},"featured_media":1829525,"template":"","meta":[],"product_brand":[],"product_cat":[85927],"product_tag":[],"class_list":["post-355444","product","type-product","status-publish","has-post-thumbnail","product_cat-runde-einbauleuchten-kardanisch","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/www.arclite-shop.de\/en\/wp-json\/wp\/v2\/product\/355444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arclite-shop.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.arclite-shop.de\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arclite-shop.de\/en\/wp-json\/wp\/v2\/media\/1829525"}],"wp:attachment":[{"href":"https:\/\/www.arclite-shop.de\/en\/wp-json\/wp\/v2\/media?parent=355444"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.arclite-shop.de\/en\/wp-json\/wp\/v2\/product_brand?post=355444"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.arclite-shop.de\/en\/wp-json\/wp\/v2\/product_cat?post=355444"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.arclite-shop.de\/en\/wp-json\/wp\/v2\/product_tag?post=355444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}