{"id":354203,"date":"2024-10-31T18:03:41","date_gmt":"2024-10-31T17:03:41","guid":{"rendered":"https:\/\/www.arclite-shop.de\/produkt\/847-35040376j802\/"},"modified":"2026-07-02T13:56:46","modified_gmt":"2026-07-02T11:56:46","slug":"847-35040376j802","status":"publish","type":"product","link":"https:\/\/www.arclite-shop.de\/en\/produkt\/847-35040376j802\/","title":{"rendered":"Odion XS - BLE Track Spotlight Swivel Black\/White 32W 37\u00b0 4000K CRI80 847-35040376J802"},"content":{"rendered":"<p>Eleganter LED-Schienenstrahle mit integrierter Betriebsger\u00e4t im Adapter, nach der Installation nicht sichtbar. LED-Streifen mit hoher Effizienz. Minimale Blendwirkung durch optimale Lichttechnik. Drehbereich 355\u00b0. Schwenkbereich 90\u00b0. Farbtoleranz 3 SDCM. Lichtstromr\u00fcckgang L90\/B10 nach mehr als 60.000h bei ta 25\u00b0C. \u201cin-trac\u201d 3-Phasen Adapter mit integriertem Betriebsger\u00e4t, flickerfrei. 7 Jahre Garantie<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eleganter LED-Schienenstrahle mit integrierter Betriebsger\u00e4t im Adapter, nach der Installation nicht sichtbar. LED-Streifen mit hoher Effizienz. Minimale Blendwirkung durch optimale Lichttechnik. Drehbereich 355\u00b0. Schwenkbereich 90\u00b0. Farbtoleranz 3 SDCM. Lichtstromr\u00fcckgang L90\/B10 nach mehr als 60.000h bei ta 25\u00b0C. \u201cin-trac\u201d 3-Phasen Adapter<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"featured_media":2505683,"template":"","meta":[],"product_brand":[],"product_cat":[86608],"product_tag":[],"class_list":["post-354203","product","type-product","status-publish","has-post-thumbnail","product_cat-schienenstrahler-dreh-schwenkbar-illuxtron","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/www.arclite-shop.de\/en\/wp-json\/wp\/v2\/product\/354203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arclite-shop.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.arclite-shop.de\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arclite-shop.de\/en\/wp-json\/wp\/v2\/media\/2505683"}],"wp:attachment":[{"href":"https:\/\/www.arclite-shop.de\/en\/wp-json\/wp\/v2\/media?parent=354203"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.arclite-shop.de\/en\/wp-json\/wp\/v2\/product_brand?post=354203"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.arclite-shop.de\/en\/wp-json\/wp\/v2\/product_cat?post=354203"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.arclite-shop.de\/en\/wp-json\/wp\/v2\/product_tag?post=354203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}