{"id":346022,"date":"2024-10-31T11:13:45","date_gmt":"2024-10-31T10:13:45","guid":{"rendered":"https:\/\/www.arclite-shop.de\/produkt\/476-ae82348-01-92\/"},"modified":"2026-07-02T16:31:23","modified_gmt":"2026-07-02T14:31:23","slug":"476-ae82348-01-92","status":"publish","type":"product","link":"https:\/\/www.arclite-shop.de\/en\/produkt\/476-ae82348-01-92\/","title":{"rendered":"roundCENTURY 85 - Round recessed luminaires rigid silver  25W 24\u00b0 4000K CRI92 AE82348.01.92"},"content":{"rendered":"<p>LED Einbauleuchte f\u00fcr dekorative Beleuchtung. Entblendende Ausleuchtung durch zur\u00fcckgesetzte Optik. Facettierter Reflektor f\u00fcr optimale Lichtverteilung. Farbtoleranz 3 SDCM. Lichtstromr\u00fcckgang nach 50.000h L80\/B20. Separates, nicht dimmbares Betriebsger\u00e4t. 5 Jahre Garantie<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LED Einbauleuchte f\u00fcr dekorative Beleuchtung. Entblendende Ausleuchtung durch zur\u00fcckgesetzte Optik. Facettierter Reflektor f\u00fcr optimale Lichtverteilung. Farbtoleranz 3 SDCM. Lichtstromr\u00fcckgang nach 50.000h L80\/B20. Separates, nicht dimmbares Betriebsger\u00e4t. 5 Jahre Garantie<\/p>\n","protected":false},"featured_media":2679727,"template":"","meta":[],"product_brand":[],"product_cat":[86014],"product_tag":[],"class_list":["post-346022","product","type-product","status-publish","has-post-thumbnail","product_cat-runde-einbauleuchten-starr","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/www.arclite-shop.de\/en\/wp-json\/wp\/v2\/product\/346022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arclite-shop.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.arclite-shop.de\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arclite-shop.de\/en\/wp-json\/wp\/v2\/media\/2679727"}],"wp:attachment":[{"href":"https:\/\/www.arclite-shop.de\/en\/wp-json\/wp\/v2\/media?parent=346022"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.arclite-shop.de\/en\/wp-json\/wp\/v2\/product_brand?post=346022"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.arclite-shop.de\/en\/wp-json\/wp\/v2\/product_cat?post=346022"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.arclite-shop.de\/en\/wp-json\/wp\/v2\/product_tag?post=346022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}